{"id":12318,"count":1,"description":"","link":"https:\/\/purecab.com\/tr\/genuine-number\/3786649m2","name":"3786649M2","slug":"3786649m2","taxonomy":"genuine-number","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/purecab.com\/tr\/wp-json\/wp\/v2\/genuine-number\/12318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/purecab.com\/tr\/wp-json\/wp\/v2\/genuine-number"}],"about":[{"href":"https:\/\/purecab.com\/tr\/wp-json\/wp\/v2\/taxonomies\/genuine-number"}],"wp:post_type":[{"href":"https:\/\/purecab.com\/tr\/wp-json\/wp\/v2\/filter-products?genuine-number=12318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}