{"id":11875,"count":1,"description":"","link":"https:\/\/purecab.com\/tr\/genuine-number\/al225554","name":"AL225554","slug":"al225554","taxonomy":"genuine-number","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/purecab.com\/tr\/wp-json\/wp\/v2\/genuine-number\/11875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/purecab.com\/tr\/wp-json\/wp\/v2\/genuine-number"}],"about":[{"href":"https:\/\/purecab.com\/tr\/wp-json\/wp\/v2\/taxonomies\/genuine-number"}],"wp:post_type":[{"href":"https:\/\/purecab.com\/tr\/wp-json\/wp\/v2\/filter-products?genuine-number=11875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}