{"id":10521,"count":1,"description":"","link":"https:\/\/purecab.com\/tr\/genuine-number\/72620540","name":"72620540","slug":"72620540","taxonomy":"genuine-number","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/purecab.com\/tr\/wp-json\/wp\/v2\/genuine-number\/10521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/purecab.com\/tr\/wp-json\/wp\/v2\/genuine-number"}],"about":[{"href":"https:\/\/purecab.com\/tr\/wp-json\/wp\/v2\/taxonomies\/genuine-number"}],"wp:post_type":[{"href":"https:\/\/purecab.com\/tr\/wp-json\/wp\/v2\/filter-products?genuine-number=10521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}