{"id":10479,"count":1,"description":"","link":"https:\/\/purecab.com\/tr\/genuine-number\/ts06453015316","name":"TS06453015316","slug":"ts06453015316","taxonomy":"genuine-number","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/purecab.com\/tr\/wp-json\/wp\/v2\/genuine-number\/10479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/purecab.com\/tr\/wp-json\/wp\/v2\/genuine-number"}],"about":[{"href":"https:\/\/purecab.com\/tr\/wp-json\/wp\/v2\/taxonomies\/genuine-number"}],"wp:post_type":[{"href":"https:\/\/purecab.com\/tr\/wp-json\/wp\/v2\/filter-products?genuine-number=10479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}