{"id":12762,"count":1,"description":"","link":"https:\/\/purecab.com\/sv\/genuine-number\/ax9567","name":"AX9567","slug":"ax9567","taxonomy":"genuine-number","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/purecab.com\/sv\/wp-json\/wp\/v2\/genuine-number\/12762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/purecab.com\/sv\/wp-json\/wp\/v2\/genuine-number"}],"about":[{"href":"https:\/\/purecab.com\/sv\/wp-json\/wp\/v2\/taxonomies\/genuine-number"}],"wp:post_type":[{"href":"https:\/\/purecab.com\/sv\/wp-json\/wp\/v2\/filter-products?genuine-number=12762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}