{"id":10436,"count":1,"description":"","link":"https:\/\/purecab.com\/sv\/genuine-number\/334-s0776","name":"334-S0776","slug":"334-s0776","taxonomy":"genuine-number","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/purecab.com\/sv\/wp-json\/wp\/v2\/genuine-number\/10436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/purecab.com\/sv\/wp-json\/wp\/v2\/genuine-number"}],"about":[{"href":"https:\/\/purecab.com\/sv\/wp-json\/wp\/v2\/taxonomies\/genuine-number"}],"wp:post_type":[{"href":"https:\/\/purecab.com\/sv\/wp-json\/wp\/v2\/filter-products?genuine-number=10436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}