{"id":8867,"count":1,"description":"","link":"https:\/\/purecab.com\/pl\/genuine-number\/47548101","name":"47548101","slug":"47548101","taxonomy":"genuine-number","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/purecab.com\/pl\/wp-json\/wp\/v2\/genuine-number\/8867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/purecab.com\/pl\/wp-json\/wp\/v2\/genuine-number"}],"about":[{"href":"https:\/\/purecab.com\/pl\/wp-json\/wp\/v2\/taxonomies\/genuine-number"}],"wp:post_type":[{"href":"https:\/\/purecab.com\/pl\/wp-json\/wp\/v2\/filter-products?genuine-number=8867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}