{"id":13712,"count":1,"description":"","link":"https:\/\/purecab.com\/da\/genuine-number\/1262218","name":"1262218","slug":"1262218","taxonomy":"genuine-number","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/purecab.com\/da\/wp-json\/wp\/v2\/genuine-number\/13712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/purecab.com\/da\/wp-json\/wp\/v2\/genuine-number"}],"about":[{"href":"https:\/\/purecab.com\/da\/wp-json\/wp\/v2\/taxonomies\/genuine-number"}],"wp:post_type":[{"href":"https:\/\/purecab.com\/da\/wp-json\/wp\/v2\/filter-products?genuine-number=13712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}